{"id":3429,"count":1,"description":"","link":"https:\/\/yes-ternopil.com.ua\/ru\/tag\/pokupka-akczij","name":"\u043f\u043e\u043a\u0443\u043f\u043a\u0430 \u0430\u043a\u0446\u0438\u0439","slug":"pokupka-akczij","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags\/3429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=3429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}