{"id":2916,"count":1,"description":"","link":"https:\/\/yes-ternopil.com.ua\/ru\/tag\/%d0%be%d0%bf%d0%b5%d1%80%d0%b0%d1%86%d0%b8%d1%8f","name":"\u043e\u043f\u0435\u0440\u0430\u0446\u0438\u044f","slug":"%d0%be%d0%bf%d0%b5%d1%80%d0%b0%d1%86%d0%b8%d1%8f","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags\/2916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=2916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}