{"id":2845,"count":1,"description":"","link":"https:\/\/yes-ternopil.com.ua\/ru\/tag\/%d1%86%d0%b5%d0%bd%d1%8b-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b4%d1%83%d0%ba%d1%82%d1%8b-%d0%bd%d0%b0-%d1%82%d0%b5%d1%80%d0%bd%d0%be%d0%bf%d0%be%d0%bb%d1%8c%d1%89%d0%b8%d0%bd%d0%b5","name":"\u0446\u0435\u043d\u044b \u043d\u0430 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b \u043d\u0430 \u0442\u0435\u0440\u043d\u043e\u043f\u043e\u043b\u044c\u0449\u0438\u043d\u0435","slug":"%d1%86%d0%b5%d0%bd%d1%8b-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b4%d1%83%d0%ba%d1%82%d1%8b-%d0%bd%d0%b0-%d1%82%d0%b5%d1%80%d0%bd%d0%be%d0%bf%d0%be%d0%bb%d1%8c%d1%89%d0%b8%d0%bd%d0%b5","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags\/2845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=2845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}