{"id":2568,"count":1,"description":"","link":"https:\/\/yes-ternopil.com.ua\/ru\/tag\/v-ternopole-obsudili-finansovuyu-podderzhku-proektov-za-dengi-oblastnogo-byudzheta","name":"\u0412 \u0422\u0435\u0440\u043d\u043e\u043f\u043e\u043b\u0435 \u043e\u0431\u0441\u0443\u0434\u0438\u043b\u0438 \u0444\u0438\u043d\u0430\u043d\u0441\u043e\u0432\u0443\u044e \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u043a\u0443 \u043f\u0440\u043e\u0435\u043a\u0442\u043e\u0432 \u0437\u0430 \u0434\u0435\u043d\u044c\u0433\u0438 \u043e\u0431\u043b\u0430\u0441\u0442\u043d\u043e\u0433\u043e \u0431\u044e\u0434\u0436\u0435\u0442\u0430","slug":"v-ternopole-obsudili-finansovuyu-podderzhku-proektov-za-dengi-oblastnogo-byudzheta","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}