{"id":1401,"count":1,"description":"","link":"https:\/\/yes-ternopil.com.ua\/ru\/tag\/gde-kupit-apple-iphone-11-pro-max","name":"\u0433\u0434\u0435 \u043a\u0443\u043f\u0438\u0442\u044c Apple iPhone 11 Pro Max","slug":"gde-kupit-apple-iphone-11-pro-max","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yes-ternopil.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}